{"id":117,"date":"2026-08-20T06:14:15","date_gmt":"2026-08-20T06:14:15","guid":{"rendered":"https:\/\/new.clubpadelciutadella.com\/?page_id=117"},"modified":"2026-09-02T09:48:06","modified_gmt":"2026-09-02T09:48:06","slug":"reservar-pista","status":"publish","type":"page","link":"https:\/\/www.clubpadelciutadella.com\/es\/reservar-pista\/","title":{"rendered":"Reserva"},"content":{"rendered":"<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group anima is-layout-constrained wp-container-core-group-is-layout-10e56c34 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<h2 class=\"wp-block-heading has-text-align-center display-3 text-primary\" style=\"font-size:60px\">Reserva pista<\/h2>\n\n\n\n<p class=\"has-text-align-center lead text-secondary text-center mb-4 wp-block-paragraph\">Fes la teva reserva des de l&#8217;app<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center has-primary-color has-text-color has-link-color wp-elements-1\">1. Descarrega l&#8217;app<\/h3>\n\n\n\n<p class=\"has-text-align-center alignwide has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-2 wp-block-paragraph\">Cerca Resasports a l&#8217;App Store o Google Play<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons alignwide is-vertical is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-f9faaab3 gap-1 mb-3\">\n<div class=\"wp-block-button is-style-outline boto-ios\"><a class=\"wp-block-button__link has-white-color has-primary-background-color has-text-color has-background has-link-color wp-element-button btn btn-outline-primary\" href=\"https:\/\/apps.apple.com\/es\/app\/resasports\/id566330851\">Descarrega per a iPhone<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-outline boto-android\"><a class=\"wp-block-button__link has-white-color has-primary-background-color has-text-color has-background has-link-color wp-element-button btn btn-outline-primary\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.Nubapp.LesJoueurs&amp;utm_source=emea_Med\">Descarrega per a Android<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center has-primary-color has-text-color has-link-color wp-elements-3\">2. Registra&#8217;t<\/h3>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-4 wp-block-paragraph\">Crea el teu compte i selecciona Club P\u00e0del Ciutadella<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center has-primary-color has-text-color has-link-color wp-elements-5\">3. Reserva i disfruta<\/h3>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-6 wp-block-paragraph\">Tria dia, hora i pista. Ja pots jugar!<\/p>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group anima is-layout-constrained wp-container-core-group-is-layout-10e56c34 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<h4 class=\"wp-block-heading has-text-align-center has-primary-color has-text-color has-link-color has-medium-font-size wp-elements-7\">Prefereixes reservar per tel\u00e8fon?<\/h4>\n\n\n\n<div class=\"wp-block-buttons boto-whatsapp is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-3e41869c gap-1 mb-3\">\n<div class=\"wp-block-button is-style-outline\"><a class=\"wp-block-button__link has-white-color has-primary-background-color has-text-color has-background has-link-color has-text-align-center wp-element-button btn btn-outline-primary\" href=\"https:\/\/wa.me\/34606158649?text=Hola!%20Voldria%20reservar%20una%20pista\">Reserva per WhatsApp<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:200px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group anima is-layout-constrained wp-container-core-group-is-layout-10e56c34 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<h3 class=\"wp-block-heading has-text-align-center has-primary-color has-text-color has-link-color has-large-font-size wp-elements-8\">Preus de lloguer<\/h3>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color wp-elements-9 wp-block-paragraph\">Per persona i partit<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center has-primary-color has-text-color has-link-color wp-elements-10\">4 \u20ac<\/h3>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color wp-elements-11 wp-block-paragraph\">Pista \u00b7 Socis<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center alignwide has-primary-color has-text-color has-link-color wp-elements-12\">5,50 \u20ac<\/h3>\n\n\n\n<p class=\"has-text-align-center alignwide has-secondary-color has-text-color has-link-color wp-elements-13 wp-block-paragraph\">Pista \u00b7 No socis<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center alignwide has-primary-color has-text-color has-link-color wp-elements-14\">3,50 \u20ac<\/h3>\n\n\n\n<p class=\"has-text-align-center alignwide has-secondary-color has-text-color has-link-color wp-elements-15 wp-block-paragraph\">Lloguer de pala<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:200px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group anima is-layout-constrained wp-container-core-group-is-layout-10e56c34 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<h3 class=\"wp-block-heading has-text-align-center has-primary-color has-text-color has-link-color has-large-font-size wp-elements-16\">Com fer-ho, pas a pas<\/h3>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-17 wp-block-paragraph\">Guia visual per registrar-te i reservar<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"1024\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-474x1024.jpeg\" alt=\"\" class=\"wp-image-391\" style=\"width:auto;height:500px\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-474x1024.jpeg 474w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-139x300.jpeg 139w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-768x1661.jpeg 768w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-710x1536.jpeg 710w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37.jpeg 947w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-18 wp-block-paragraph\">1. Descarrega l&#8217;app<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"1024\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.29-474x1024.jpeg\" alt=\"\" class=\"wp-image-392\" style=\"width:auto;height:500px\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.29-474x1024.jpeg 474w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.29-139x300.jpeg 139w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.29-768x1661.jpeg 768w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.29-710x1536.jpeg 710w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.29.jpeg 947w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-19 wp-block-paragraph\">2. Crea el teu compte<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"1024\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-1-474x1024.jpeg\" alt=\"\" class=\"wp-image-388\" style=\"width:auto;height:500px\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-1-474x1024.jpeg 474w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-1-139x300.jpeg 139w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-1-768x1661.jpeg 768w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-1-710x1536.jpeg 710w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-1.jpeg 947w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-20 wp-block-paragraph\">3. Emplena les teves dades<\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"1024\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-474x1024.jpeg\" alt=\"\" class=\"wp-image-389\" style=\"width:auto;height:500px\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-474x1024.jpeg 474w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-139x300.jpeg 139w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-768x1661.jpeg 768w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38-710x1536.jpeg 710w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.38.jpeg 947w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-21 wp-block-paragraph\">4. Cerca el club<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"1024\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-1-474x1024.jpeg\" alt=\"\" class=\"wp-image-390\" style=\"width:auto;height:500px\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-1-474x1024.jpeg 474w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-1-139x300.jpeg 139w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-1-768x1661.jpeg 768w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-1-710x1536.jpeg 710w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-1.jpeg 947w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-22 wp-block-paragraph\">5. Accepta les condicions<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"1024\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.28-474x1024.jpeg\" alt=\"\" class=\"wp-image-393\" style=\"width:auto;height:500px\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.28-474x1024.jpeg 474w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.28-139x300.jpeg 139w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.28-768x1661.jpeg 768w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.28-710x1536.jpeg 710w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.28.jpeg 947w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color has-medium-font-size wp-elements-23 wp-block-paragraph\">6. Ja pots reservar<\/p>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:200px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-layout-constrained wp-container-core-group-is-layout-10e56c34 wp-block-group-is-layout-constrained\" style=\"padding-right:var(--wp--preset--spacing--50);padding-left:var(--wp--preset--spacing--50)\">\n<h2 class=\"wp-block-heading has-text-align-center has-primary-color has-text-color has-link-color wp-elements-24\" style=\"font-size:50px\">Patrocinadors<\/h2>\n\n\n\n<p class=\"has-text-align-center has-secondary-color has-text-color has-link-color wp-elements-25 wp-block-paragraph\">Gr\u00e0cies a la seva confian\u00e7a, fem possible el p\u00e0del a Ciutadella<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large has-custom-css wp-custom-css-507aa37b\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"507\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Galp2-1024x507.png\" alt=\"\" class=\"wp-image-216\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Galp2-1024x507.png 1024w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Galp2-300x149.png 300w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Galp2-767x380.png 767w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Galp2-1536x761.png 1536w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Galp2.png 1688w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large has-custom-css wp-custom-css-5b6db5d9\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"511\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bp2-1024x511.png\" alt=\"\" class=\"wp-image-220\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bp2-1024x511.png 1024w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bp2-300x150.png 300w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bp2-768x383.png 768w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bp2-1536x766.png 1536w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bp2.png 1692w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large has-custom-css wp-custom-css-26122417\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"463\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Sin-titulo-1024x463.png\" alt=\"\" class=\"wp-image-222\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Sin-titulo-1024x463.png 1024w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Sin-titulo-300x136.png 300w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Sin-titulo-768x347.png 768w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Sin-titulo-1536x694.png 1536w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/Sin-titulo.png 1894w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large has-custom-css wp-custom-css-c05bf2bd\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"676\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bananas2-1024x676.png\" alt=\"\" class=\"wp-image-224\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bananas2-1024x676.png 1024w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bananas2-300x198.png 300w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bananas2-767x506.png 767w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/bananas2.png 1388w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large has-custom-css wp-custom-css-a1ea6e29\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"563\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/hidrop-1024x563.png\" alt=\"\" class=\"wp-image-225\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/hidrop-1024x563.png 1024w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/hidrop-300x165.png 300w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/hidrop-767x422.png 767w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/hidrop.png 1147w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large has-custom-css wp-custom-css-2342c1af\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/LOGO_DOSOPTICS_COLOR_pages-to-jpg-0001-1024x724.jpg\" alt=\"\" class=\"wp-image-223\" srcset=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/LOGO_DOSOPTICS_COLOR_pages-to-jpg-0001-1024x724.jpg 1024w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/LOGO_DOSOPTICS_COLOR_pages-to-jpg-0001-300x212.jpg 300w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/LOGO_DOSOPTICS_COLOR_pages-to-jpg-0001-767x542.jpg 767w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/LOGO_DOSOPTICS_COLOR_pages-to-jpg-0001-1536x1086.jpg 1536w, https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/08\/LOGO_DOSOPTICS_COLOR_pages-to-jpg-0001-2048x1448.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Reserva pista Fes la teva reserva des de l&#8217;app 1. Descarrega l&#8217;app Cerca Resasports a l&#8217;App Store o Google Play 2. Registra&#8217;t Crea el teu compte i selecciona Club P\u00e0del Ciutadella 3. Reserva i disfruta Tria dia, hora i pista. Ja pots jugar! Prefereixes reservar per tel\u00e8fon? Preus de lloguer Per persona i partit 4 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/page-blank.php","meta":{"footnotes":""},"class_list":["post-117","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reserva - Club P\u00e0del Ciutadella<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.clubpadelciutadella.com\/es\/reservar-pista\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reserva - Club P\u00e0del Ciutadella\" \/>\n<meta property=\"og:description\" content=\"Reserva pista Fes la teva reserva des de l&#8217;app 1. Descarrega l&#8217;app Cerca Resasports a l&#8217;App Store o Google Play 2. Registra&#8217;t Crea el teu compte i selecciona Club P\u00e0del Ciutadella 3. Reserva i disfruta Tria dia, hora i pista. Ja pots jugar! Prefereixes reservar per tel\u00e8fon? Preus de lloguer Per persona i partit 4 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.clubpadelciutadella.com\/es\/reservar-pista\/\" \/>\n<meta property=\"og:site_name\" content=\"Club P\u00e0del Ciutadella\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T09:48:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"947\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/reservar-pista\\\/\",\"url\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/reservar-pista\\\/\",\"name\":\"Reserva - Club P\u00e0del Ciutadella\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/reservar-pista\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/reservar-pista\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/WhatsApp-Image-2026-09-01-at-06.22.37-474x1024.jpeg\",\"datePublished\":\"2026-08-20T06:14:15+00:00\",\"dateModified\":\"2026-09-02T09:48:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/reservar-pista\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.clubpadelciutadella.com\\\/reservar-pista\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/reservar-pista\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/WhatsApp-Image-2026-09-01-at-06.22.37-474x1024.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/WhatsApp-Image-2026-09-01-at-06.22.37-474x1024.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/reservar-pista\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reserva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/#website\",\"url\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/\",\"name\":\"Club P\u00e0del Ciutadella\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.clubpadelciutadella.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reserva - Club P\u00e0del Ciutadella","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.clubpadelciutadella.com\/es\/reservar-pista\/","og_locale":"es_ES","og_type":"article","og_title":"Reserva - Club P\u00e0del Ciutadella","og_description":"Reserva pista Fes la teva reserva des de l&#8217;app 1. Descarrega l&#8217;app Cerca Resasports a l&#8217;App Store o Google Play 2. Registra&#8217;t Crea el teu compte i selecciona Club P\u00e0del Ciutadella 3. Reserva i disfruta Tria dia, hora i pista. Ja pots jugar! Prefereixes reservar per tel\u00e8fon? Preus de lloguer Per persona i partit 4 [&hellip;]","og_url":"https:\/\/www.clubpadelciutadella.com\/es\/reservar-pista\/","og_site_name":"Club P\u00e0del Ciutadella","article_modified_time":"2026-09-02T09:48:06+00:00","og_image":[{"width":947,"height":2048,"url":"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.clubpadelciutadella.com\/reservar-pista\/","url":"https:\/\/www.clubpadelciutadella.com\/reservar-pista\/","name":"Reserva - Club P\u00e0del Ciutadella","isPartOf":{"@id":"https:\/\/www.clubpadelciutadella.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.clubpadelciutadella.com\/reservar-pista\/#primaryimage"},"image":{"@id":"https:\/\/www.clubpadelciutadella.com\/reservar-pista\/#primaryimage"},"thumbnailUrl":"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-474x1024.jpeg","datePublished":"2026-08-20T06:14:15+00:00","dateModified":"2026-09-02T09:48:06+00:00","breadcrumb":{"@id":"https:\/\/www.clubpadelciutadella.com\/reservar-pista\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.clubpadelciutadella.com\/reservar-pista\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.clubpadelciutadella.com\/reservar-pista\/#primaryimage","url":"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-474x1024.jpeg","contentUrl":"https:\/\/www.clubpadelciutadella.com\/wp-content\/uploads\/2026\/09\/WhatsApp-Image-2026-09-01-at-06.22.37-474x1024.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.clubpadelciutadella.com\/reservar-pista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.clubpadelciutadella.com\/"},{"@type":"ListItem","position":2,"name":"Reserva"}]},{"@type":"WebSite","@id":"https:\/\/www.clubpadelciutadella.com\/#website","url":"https:\/\/www.clubpadelciutadella.com\/","name":"Club P\u00e0del Ciutadella","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.clubpadelciutadella.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.clubpadelciutadella.com\/es\/wp-json\/wp\/v2\/pages\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.clubpadelciutadella.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.clubpadelciutadella.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.clubpadelciutadella.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.clubpadelciutadella.com\/es\/wp-json\/wp\/v2\/comments?post=117"}],"version-history":[{"count":32,"href":"https:\/\/www.clubpadelciutadella.com\/es\/wp-json\/wp\/v2\/pages\/117\/revisions"}],"predecessor-version":[{"id":478,"href":"https:\/\/www.clubpadelciutadella.com\/es\/wp-json\/wp\/v2\/pages\/117\/revisions\/478"}],"wp:attachment":[{"href":"https:\/\/www.clubpadelciutadella.com\/es\/wp-json\/wp\/v2\/media?parent=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}